{"id":180706,"date":"2023-04-13T03:23:53","date_gmt":"2023-04-13T00:23:53","guid":{"rendered":"https:\/\/a-b.ee\/product\/kanada-mundi-sertifikaat-250120-231\/"},"modified":"2023-04-13T03:23:53","modified_gmt":"2023-04-13T00:23:53","slug":"kanada-mundi-sertifikaat-250120-231","status":"publish","type":"product","link":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/","title":{"rendered":"Kanada M\u00fcndi sertifikaat 250120-231"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7565,"template":"","meta":[],"product_brand":[],"product_cat":[128],"product_tag":[],"class_list":{"0":"post-180706","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pohja-ameerika-mundid","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kanada M\u00fcndi sertifikaat 250120-231 - Antique Boutique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kanada M\u00fcndi sertifikaat 250120-231\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/\" \/>\n<meta property=\"og:site_name\" content=\"Antique Boutique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antiqueboutiqueeurope\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"0,50&nbsp;&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/\",\"url\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/\",\"name\":\"Kanada M\u00fcndi sertifikaat 250120-231 - Antique Boutique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-04-13T00:23:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/a-b.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/a-b.ee\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kanada M\u00fcndi sertifikaat 250120-231\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/a-b.ee\\\/en\\\/\",\"name\":\"Antique Boutique\",\"description\":\"Antique Boutique\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-b.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/#organization\",\"name\":\"Antique Boutique\",\"alternateName\":\"Antique-Boutique\",\"url\":\"https:\\\/\\\/a-b.ee\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/antiqueboutiqueeurope\\\/\",\"https:\\\/\\\/www.instagram.com\\\/antiqueboutiqueeurope\\\/\"],\"address\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#local-main-place-address\"},\"telephone\":[\"+372 5555 5777\"],\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"info@a-b.ee\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#local-main-place-address\",\"streetAddress\":\"Loo 2\",\"addressLocality\":\"Tallinn\",\"postalCode\":\"11212\",\"addressRegion\":\"Harjumaa\",\"addressCountry\":\"EE\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/en\\\/product\\\/kanada-mundi-sertifikaat-250120-231\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/antique-boutique-500x67-black.jpg\",\"contentUrl\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/antique-boutique-500x67-black.jpg\",\"width\":500,\"height\":67,\"caption\":\"Antique Boutique\"}]}<\/script>\n<meta property=\"product:brand\" content=\"simple\" \/>\n<meta property=\"product:price:amount\" content=\"0.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"154523702\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Tallinn\" \/>\n<meta name=\"geo.region\" content=\"Estonia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kanada M\u00fcndi sertifikaat 250120-231 - Antique Boutique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/","og_locale":"en_US","og_type":"article","og_title":"Kanada M\u00fcndi sertifikaat 250120-231","og_url":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/","og_site_name":"Antique Boutique","article_publisher":"https:\/\/www.facebook.com\/antiqueboutiqueeurope\/","twitter_card":"summary_large_image","twitter_misc":{"Price":"0,50&nbsp;&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/","url":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/","name":"Kanada M\u00fcndi sertifikaat 250120-231 - Antique Boutique","isPartOf":{"@id":"https:\/\/a-b.ee\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#primaryimage"},"image":{"@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-04-13T00:23:53+00:00","breadcrumb":{"@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/a-b.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/a-b.ee\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Kanada M\u00fcndi sertifikaat 250120-231"}]},{"@type":"WebSite","@id":"https:\/\/a-b.ee\/en\/#website","url":"https:\/\/a-b.ee\/en\/","name":"Antique Boutique","description":"Antique Boutique","publisher":{"@id":"https:\/\/a-b.ee\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-b.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/a-b.ee\/en\/#organization","name":"Antique Boutique","alternateName":"Antique-Boutique","url":"https:\/\/a-b.ee\/en\/","logo":{"@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#local-main-organization-logo"},"image":{"@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/antiqueboutiqueeurope\/","https:\/\/www.instagram.com\/antiqueboutiqueeurope\/"],"address":{"@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#local-main-place-address"},"telephone":["+372 5555 5777"],"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"info@a-b.ee"},{"@type":"PostalAddress","@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#local-main-place-address","streetAddress":"Loo 2","addressLocality":"Tallinn","postalCode":"11212","addressRegion":"Harjumaa","addressCountry":"EE"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-b.ee\/en\/product\/kanada-mundi-sertifikaat-250120-231\/#local-main-organization-logo","url":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/antique-boutique-500x67-black.jpg","contentUrl":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/antique-boutique-500x67-black.jpg","width":500,"height":67,"caption":"Antique Boutique"}]},"product_brand":"simple","product_price_amount":"0.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"154523702","product_condition":"new","geo.placename":"Tallinn","geo.region":"Estonia"},"_links":{"self":[{"href":"https:\/\/a-b.ee\/en\/wp-json\/wp\/v2\/product\/180706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-b.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/a-b.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a-b.ee\/en\/wp-json\/wp\/v2\/media\/7565"}],"wp:attachment":[{"href":"https:\/\/a-b.ee\/en\/wp-json\/wp\/v2\/media?parent=180706"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/a-b.ee\/en\/wp-json\/wp\/v2\/product_brand?post=180706"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/a-b.ee\/en\/wp-json\/wp\/v2\/product_cat?post=180706"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/a-b.ee\/en\/wp-json\/wp\/v2\/product_tag?post=180706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}