{"id":335744,"date":"2023-04-13T06:04:29","date_gmt":"2023-04-13T03:04:29","guid":{"rendered":"https:\/\/a-b.ee\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/"},"modified":"2023-04-13T06:04:29","modified_gmt":"2023-04-13T03:04:29","slug":"poola-5-grosz-kaasaegne-2013-a-040819-5","status":"publish","type":"product","link":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/","title":{"rendered":"Poola 5 grosz kaasaegne 2013.a 040819-5"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":335728,"template":"","meta":[],"product_brand":[],"product_cat":[198],"product_tag":[],"class_list":{"0":"post-335744","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ida-euroopa-mundid","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Poola 5 grosz kaasaegne 2013.a 040819-5 - Antique Boutique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poola 5 grosz kaasaegne 2013.a 040819-5\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Antique Boutique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antiqueboutiqueeurope\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/60823056.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"0,19&nbsp;&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/\",\"url\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/\",\"name\":\"Poola 5 grosz kaasaegne 2013.a 040819-5 - Antique Boutique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/60823056.jpg\",\"datePublished\":\"2023-04-13T03:04:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/60823056.jpg\",\"contentUrl\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/60823056.jpg\",\"width\":560,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u5546\u5e97 &#8211; Chinese Simplified\",\"item\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/%e5%95%86%e5%ba%97\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Poola 5 grosz kaasaegne 2013.a 040819-5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/\",\"name\":\"Antique Boutique\",\"description\":\"Antique Boutique\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/#organization\",\"name\":\"Antique Boutique\",\"alternateName\":\"Antique-Boutique\",\"url\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/antiqueboutiqueeurope\\\/\",\"https:\\\/\\\/www.instagram.com\\\/antiqueboutiqueeurope\\\/\"],\"address\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#local-main-place-address\"},\"telephone\":[\"+372 5555 5777\"],\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"info@a-b.ee\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#local-main-place-address\",\"streetAddress\":\"Loo 2\",\"addressLocality\":\"Tallinn\",\"postalCode\":\"11212\",\"addressRegion\":\"Harjumaa\",\"addressCountry\":\"EE\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/poola-5-grosz-kaasaegne-2013-a-040819-5\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/antique-boutique-500x67-black.jpg\",\"contentUrl\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/antique-boutique-500x67-black.jpg\",\"width\":500,\"height\":67,\"caption\":\"Antique Boutique\"}]}<\/script>\n<meta property=\"product:brand\" content=\"simple\" \/>\n<meta property=\"product:price:amount\" content=\"0.19\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"135554429\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Tallinn\" \/>\n<meta name=\"geo.region\" content=\"Estonia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Poola 5 grosz kaasaegne 2013.a 040819-5 - Antique Boutique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/","og_locale":"zh_CN","og_type":"article","og_title":"Poola 5 grosz kaasaegne 2013.a 040819-5","og_url":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/","og_site_name":"Antique Boutique","article_publisher":"https:\/\/www.facebook.com\/antiqueboutiqueeurope\/","og_image":[{"width":560,"height":560,"url":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/60823056.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"0,19&nbsp;&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/","url":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/","name":"Poola 5 grosz kaasaegne 2013.a 040819-5 - Antique Boutique","isPartOf":{"@id":"https:\/\/a-b.ee\/zh-hans\/#website"},"primaryImageOfPage":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#primaryimage"},"image":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#primaryimage"},"thumbnailUrl":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/60823056.jpg","datePublished":"2023-04-13T03:04:29+00:00","breadcrumb":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#primaryimage","url":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/60823056.jpg","contentUrl":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/60823056.jpg","width":560,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/a-b.ee\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"\u5546\u5e97 &#8211; Chinese Simplified","item":"https:\/\/a-b.ee\/zh-hans\/%e5%95%86%e5%ba%97\/"},{"@type":"ListItem","position":3,"name":"Poola 5 grosz kaasaegne 2013.a 040819-5"}]},{"@type":"WebSite","@id":"https:\/\/a-b.ee\/zh-hans\/#website","url":"https:\/\/a-b.ee\/zh-hans\/","name":"Antique Boutique","description":"Antique Boutique","publisher":{"@id":"https:\/\/a-b.ee\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-b.ee\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":["Organization","Place"],"@id":"https:\/\/a-b.ee\/zh-hans\/#organization","name":"Antique Boutique","alternateName":"Antique-Boutique","url":"https:\/\/a-b.ee\/zh-hans\/","logo":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#local-main-organization-logo"},"image":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/antiqueboutiqueeurope\/","https:\/\/www.instagram.com\/antiqueboutiqueeurope\/"],"address":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#local-main-place-address"},"telephone":["+372 5555 5777"],"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"info@a-b.ee"},{"@type":"PostalAddress","@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#local-main-place-address","streetAddress":"Loo 2","addressLocality":"Tallinn","postalCode":"11212","addressRegion":"Harjumaa","addressCountry":"EE"},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/a-b.ee\/zh-hans\/product\/poola-5-grosz-kaasaegne-2013-a-040819-5\/#local-main-organization-logo","url":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/antique-boutique-500x67-black.jpg","contentUrl":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/antique-boutique-500x67-black.jpg","width":500,"height":67,"caption":"Antique Boutique"}]},"product_brand":"simple","product_price_amount":"0.19","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"135554429","product_condition":"new","geo.placename":"Tallinn","geo.region":"Estonia"},"_links":{"self":[{"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product\/335744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/media\/335728"}],"wp:attachment":[{"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/media?parent=335744"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product_brand?post=335744"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product_cat?post=335744"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product_tag?post=335744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}