{"id":410434,"date":"2023-04-13T12:33:19","date_gmt":"2023-06-20T05:29:41","guid":{"rendered":"https:\/\/a-b.ee\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/"},"modified":"2023-06-20T08:29:41","modified_gmt":"2023-06-20T05:29:41","slug":"%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3","status":"publish","type":"product","link":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/","title":{"rendered":"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73<\/p>\n","protected":false},"featured_media":408250,"template":"","meta":[],"product_brand":[],"product_cat":[356],"product_tag":[],"class_list":{"0":"post-410434","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-356","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73 - Antique Boutique<\/title>\n<meta name=\"description\" content=\"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73\" \/>\n<meta property=\"og:description\" content=\"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/\" \/>\n<meta property=\"og:site_name\" content=\"Antique Boutique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antiqueboutiqueeurope\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/88341204.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"4,90&nbsp;&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/\",\"url\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/\",\"name\":\"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73 - Antique Boutique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/88341204.jpg\",\"datePublished\":\"2023-06-20T05:29:41+00:00\",\"description\":\"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/88341204.jpg\",\"contentUrl\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/88341204.jpg\",\"width\":560,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u5546\u5e97 &#8211; Chinese Simplified\",\"item\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/%e5%95%86%e5%ba%97\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/\",\"name\":\"Antique Boutique\",\"description\":\"Antique Boutique\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/#organization\",\"name\":\"Antique Boutique\",\"alternateName\":\"Antique-Boutique\",\"url\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/antiqueboutiqueeurope\\\/\",\"https:\\\/\\\/www.instagram.com\\\/antiqueboutiqueeurope\\\/\"],\"address\":{\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#local-main-place-address\"},\"telephone\":[\"+372 5555 5777\"],\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"info@a-b.ee\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#local-main-place-address\",\"streetAddress\":\"Loo 2\",\"addressLocality\":\"Tallinn\",\"postalCode\":\"11212\",\"addressRegion\":\"Harjumaa\",\"addressCountry\":\"EE\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/a-b.ee\\\/zh-hans\\\/product\\\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/antique-boutique-500x67-black.jpg\",\"contentUrl\":\"https:\\\/\\\/a-b.ee\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/antique-boutique-500x67-black.jpg\",\"width\":500,\"height\":67,\"caption\":\"Antique Boutique\"}]}<\/script>\n<meta property=\"product:brand\" content=\"simple\" \/>\n<meta property=\"product:price:amount\" content=\"4.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"080220-984+ Galun pael pagunidele 30mm. Kullatis-1 meeter\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Tallinn\" \/>\n<meta name=\"geo.region\" content=\"Estonia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73 - Antique Boutique","description":"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/","og_locale":"zh_CN","og_type":"article","og_title":"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73","og_description":"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73","og_url":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/","og_site_name":"Antique Boutique","article_publisher":"https:\/\/www.facebook.com\/antiqueboutiqueeurope\/","og_image":[{"width":560,"height":560,"url":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/88341204.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"4,90&nbsp;&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/","url":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/","name":"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73 - Antique Boutique","isPartOf":{"@id":"https:\/\/a-b.ee\/zh-hans\/#website"},"primaryImageOfPage":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#primaryimage"},"image":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#primaryimage"},"thumbnailUrl":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/88341204.jpg","datePublished":"2023-06-20T05:29:41+00:00","description":"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73","breadcrumb":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#primaryimage","url":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/88341204.jpg","contentUrl":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/88341204.jpg","width":560,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/a-b.ee\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"\u5546\u5e97 &#8211; Chinese Simplified","item":"https:\/\/a-b.ee\/zh-hans\/%e5%95%86%e5%ba%97\/"},{"@type":"ListItem","position":3,"name":"\u7528\u4e8e 30 \u6beb\u7c73\u957f\u67aa\u7684 Galun \u4e1d\u5e26\u3002 \u9540\u91d1-1\u7c73"}]},{"@type":"WebSite","@id":"https:\/\/a-b.ee\/zh-hans\/#website","url":"https:\/\/a-b.ee\/zh-hans\/","name":"Antique Boutique","description":"Antique Boutique","publisher":{"@id":"https:\/\/a-b.ee\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-b.ee\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":["Organization","Place"],"@id":"https:\/\/a-b.ee\/zh-hans\/#organization","name":"Antique Boutique","alternateName":"Antique-Boutique","url":"https:\/\/a-b.ee\/zh-hans\/","logo":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#local-main-organization-logo"},"image":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/antiqueboutiqueeurope\/","https:\/\/www.instagram.com\/antiqueboutiqueeurope\/"],"address":{"@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#local-main-place-address"},"telephone":["+372 5555 5777"],"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"info@a-b.ee"},{"@type":"PostalAddress","@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#local-main-place-address","streetAddress":"Loo 2","addressLocality":"Tallinn","postalCode":"11212","addressRegion":"Harjumaa","addressCountry":"EE"},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/a-b.ee\/zh-hans\/product\/%e7%94%a8%e4%ba%8e-30-%e6%af%ab%e7%b1%b3%e9%95%bf%e6%9e%aa%e7%9a%84-galun-%e4%b8%9d%e5%b8%a6%e3%80%82-%e9%95%80%e9%87%91-1%e7%b1%b3\/#local-main-organization-logo","url":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/antique-boutique-500x67-black.jpg","contentUrl":"https:\/\/a-b.ee\/wp-content\/uploads\/2023\/04\/antique-boutique-500x67-black.jpg","width":500,"height":67,"caption":"Antique Boutique"}]},"product_brand":"simple","product_price_amount":"4.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"080220-984+ Galun pael pagunidele 30mm. Kullatis-1 meeter","product_condition":"new","geo.placename":"Tallinn","geo.region":"Estonia"},"_links":{"self":[{"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product\/410434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/media\/408250"}],"wp:attachment":[{"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/media?parent=410434"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product_brand?post=410434"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product_cat?post=410434"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/a-b.ee\/zh-hans\/wp-json\/wp\/v2\/product_tag?post=410434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}